{"id":105,"date":"2023-02-21T22:24:16","date_gmt":"2023-02-21T22:24:16","guid":{"rendered":"https:\/\/2020news.de\/reloaded\/?p=105"},"modified":"2023-03-07T01:04:26","modified_gmt":"2023-03-07T01:04:26","slug":"controlled-stranding","status":"publish","type":"post","link":"https:\/\/2020news.de\/reloaded\/controlled-stranding\/","title":{"rendered":"Kontrollierte Notlandung \/Controlled Stranding"},"content":{"rendered":"\n<p>Bei Bittel TV hat Reiner Fuellmich nun alternative Fakten zu der Darstellung, dass er quasi durch Happenstance in Mexiko notuntergekommen sei, nachdem die US Beh\u00f6rden ihn nicht mehr ins Land hineinlassen wollten, vorgetragen. Wie ich ja schon im Beitrag <a href=\"https:\/\/2020news.de\/reloaded\/wo-die-rochen-springen\/\">&#8222;Wo die Rochen springen&#8220;<\/a> mitgeteilt hatte, bestand bei Reiner Fuellmich&#8217;s Ehefrau Inka ein Einreisehindernis, was Reiner Fuellmich bei Bittel TV nun auch \u00f6ffentlich best\u00e4tigt hat. Nach der neuen Sachverhaltsschilderung aus dem Hause Fuellmich wollte Inka Freunde in Mexiko besuchen, nachdem sie mit ihrem Mann in Peru den Rechtsanwalt Michael Swinwood und eine Inca-Hohepriesterin getroffen hatte. Reiner Fuellmich will sich diesen Reisepl\u00e4nen spontan angeschlossen haben, nachdem ihm angeblich der Flug aus Peru in die USA verweigert worden sei. Ob es stimmt, dass Reiner Fuellmich nicht in die USA einreisen darf, wird sich zeigen. Die Story, dass das Ehepaar Fuellmich nur aufgrund von sich pl\u00f6tzlich ergebenden Einreiseproblemen in Mexiko notgestrandet sind und nur durch gro\u00dfes Gl\u00fcck bei neuen Freunden aus Oregon untergekommen ist, stimmt jedenfalls nicht. Der Aufenthalt unter mexikanischer Sonne d\u00fcrfte vorbereitet gewesen sein. <\/p>\n\n\n\n<p>Was bisher geschah: Die Internas vom Corona-Ausschuss mit n\u00e4herer Darstellung der \u201eUngereimtheiten\u201c im&nbsp;<a href=\"https:\/\/2020shop.de\/startseite\/23-homo-amicus.html\">Buch HOMO AMICUS (reloaded)<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>At Bittel TV Reiner Fuellmich has now presented alternative facts to the account that he had found refuge in Mexico quasi through happenstance after the US authorities no longer wanted to let him into the country. As I had already communicated in the contribution &#8222;Where the rays jump&#8220; Reiner Fuellmich&#8217;s wife Inka was facing an entry obstacle. This fact has now been publicly confirmed by Reiner Fuellmich at Bittel TV. According to the new narrative from the house of Fuellmich, Inka wanted to visit friends in Mexico, after she had met the lawyer Michael Swinwood and an Inca high priestess with her husband in Peru. Reiner Fuellmich claims to have spontaneously joined these travel plans after he was allegedly denied a flight from Peru to the USA. Whether it is true that Reiner Fuellmich is not allowed to enter the USA remains to be seen. The story that the couple Fuellmich are stranded in Mexico only because of suddenly arising entry problems and only by great luck were invited by their new friends from Oregon, is not true in any case. It is looking like the stay under the Mexican sun has been well prepared.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei Bittel TV hat Reiner Fuellmich nun alternative Fakten zu der Darstellung, dass er quasi durch Happenstance in Mexiko notuntergekommen sei, nachdem die US Beh\u00f6rden ihn nicht mehr ins Land hineinlassen wollten, vorgetragen. Wie ich ja schon im Beitrag &#8222;Wo die Rochen springen&#8220; mitgeteilt hatte, bestand bei Reiner Fuellmich&#8217;s Ehefrau Inka ein Einreisehindernis, was Reiner&hellip; <a class=\"more-link\" href=\"https:\/\/2020news.de\/reloaded\/controlled-stranding\/\"><span class=\"screen-reader-text\">Kontrollierte Notlandung \/Controlled Stranding<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4],"tags":[],"class_list":["post-105","post","type-post","status-publish","format-standard","hentry","category-buch","category-mexiko","entry"],"_links":{"self":[{"href":"https:\/\/2020news.de\/reloaded\/wp-json\/wp\/v2\/posts\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/2020news.de\/reloaded\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/2020news.de\/reloaded\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/2020news.de\/reloaded\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/2020news.de\/reloaded\/wp-json\/wp\/v2\/comments?post=105"}],"version-history":[{"count":4,"href":"https:\/\/2020news.de\/reloaded\/wp-json\/wp\/v2\/posts\/105\/revisions"}],"predecessor-version":[{"id":131,"href":"https:\/\/2020news.de\/reloaded\/wp-json\/wp\/v2\/posts\/105\/revisions\/131"}],"wp:attachment":[{"href":"https:\/\/2020news.de\/reloaded\/wp-json\/wp\/v2\/media?parent=105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/2020news.de\/reloaded\/wp-json\/wp\/v2\/categories?post=105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/2020news.de\/reloaded\/wp-json\/wp\/v2\/tags?post=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}